{"id":1735,"date":"2020-02-11T12:04:53","date_gmt":"2020-02-11T11:04:53","guid":{"rendered":"http:\/\/fluidworkssuspension.com\/store\/?post_type=product&#038;p=1735"},"modified":"2025-08-26T10:36:50","modified_gmt":"2025-08-26T08:36:50","slug":"rockshox-super-deluxe","status":"publish","type":"product","link":"https:\/\/fluidworkssuspension.com\/store\/prodotto\/rockshox-super-deluxe\/","title":{"rendered":"RockShox Super Deluxe"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h2>Ammortizzatore RockShox Super Deluxe Air<\/h2>\n<h3>Revisione completa<\/h3>\n<p>Effettuiamo la revisione completa del tuo ammortizzatore RockShox Super Deluxe, clicca i pulsanti seguenti per scoprire cosa comprende:<\/p>\n\n<div class=\"panel-group\" id=\"accordionname53\"><div class=\"panel panel-default panel-even\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname53\" href=\"#collapse530\"><h5><i class=\"icon-minus primary-color\"><\/i><i class=\"icon-plus\"><\/i>Cosa comprende la revisione per RockShox Super Deluxe Air <\/h5><\/a><\/div><div id=\"collapse530\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<p><strong>Revisione completa Ammortizzatore RockShox Super Deluxe Air<\/strong><\/p>\n<p>Gli interventi di revisione completa per gli ammortizzatori RockShox Deluxe Air comprendono:<\/p>\n<ul>\n<li>smontaggio<\/li>\n<li>pulizia e sgrassaggio in profondit\u00e0<\/li>\n<li>ispezione per eventuale usura anomala etc<\/li>\n<li>sostituzione ed aggiornamento elementi di tenuta aria\/olio<\/li>\n<li>rimontaggio con utilizzo di prodotti specifici (adesivo anaerobico sigillante sulle filettature , grasso ad altissima scorrevolezza specifico per sospensioni, lubricanti specifici)<\/li>\n<li>spurgo multiplo sottovuoto con pompa Andreani semi-automatica digitale ed olio Ohlins\u00a0(garantisce assenza di aria nel circuito idraulico-molto intricato-\u00a0garantendo costanza e durata delle prestazioni)<\/li>\n<li>Pressurizzazione IFP con azoto<\/li>\n<li>sostituzione boccole DU se necessario (allegare sempre i riduttori)<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<div class=\"panel panel-default panel-odd\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname53\" href=\"#collapse531\"><h5><i class=\"icon-minus primary-color\"><\/i><i class=\"icon-plus\"><\/i>Disponibile per le seguenti versioni<\/h5><\/a><\/div><div id=\"collapse531\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<p><strong>La revisione completa \u00e8 disponibile per i seguenti modelli di ammortizzatore RockShox Super Deluxe Air:<\/strong><\/p>\n<ul>\n<li>RockShox Super Deluxe Air Select, Select+, Ultimate, Ultimate DH, Ultimate Remote<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<div class=\"panel panel-default panel-even\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname53\" href=\"#collapse532\"><h5><i class=\"icon-minus primary-color\"><\/i><i class=\"icon-plus\"><\/i>Tuning<\/h5><\/a><\/div><div id=\"collapse532\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<p><strong>Le opzioni possibili di tuning per questo ammortizzatore sono:<\/strong><\/p>\n<ul>\n<li>Aumento progressivit\u00e0 (riduzione volume camere pneumatiche)<\/li>\n<li>Taratura idraulica specifica (da indicare sulle note d&#8217;ordine)<\/li>\n<li>ProImpact by Andreani<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"<div class=\"woocommerce-product-details__short-description\">\n<div class=\"woocommerce-product-details__short-description\">\n<p>Scegli la tipologia di service\/tuning che ti interessa:<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":1739,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[18,41,43],"product_tag":[],"_links":{"self":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product\/1735"}],"collection":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/comments?post=1735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/media\/1739"}],"wp:attachment":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/media?parent=1735"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product_cat?post=1735"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product_tag?post=1735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}