{"id":3057,"date":"2024-01-26T11:01:32","date_gmt":"2024-01-26T10:01:32","guid":{"rendered":"http:\/\/fluidworkssuspension.com\/store\/?post_type=product&#038;p=3057"},"modified":"2025-09-26T08:24:49","modified_gmt":"2025-09-26T06:24:49","slug":"cane-creek-db-kitsuma-air","status":"publish","type":"product","link":"https:\/\/fluidworkssuspension.com\/store\/prodotto\/cane-creek-db-kitsuma-air\/","title":{"rendered":"Cane Creek DB Kitsuma Air"},"content":{"rendered":"<h2>Ammortizzatore Cane Creek DB Kitsuma Air<\/h2>\n<p>Effettuiamo la manutenzione completa del tuo ammortizzatore CCDB Kitsuma Air, clicca i pulsanti seguenti per scoprire cosa comprende:<\/p>\n\n<div class=\"panel-group\" id=\"accordionname11\"><div class=\"panel panel-default panel-even\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname11\" href=\"#collapse110\"><h5><i class=\"icon-minus primary-color\"><\/i><i class=\"icon-plus\"><\/i>Cosa comprende la manutenzione per CCDB Kitsuma Air<\/h5><\/a><\/div><div id=\"collapse110\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<p><strong>Revisione completa Ammortizzatore CCDB Kitsuma Air<br \/>\n<\/strong><\/p>\n<p>Gli interventi di revisione per gli ammortizzatori CCDB Kitsuma Air comprendono:<\/p>\n<ul>\n<li>annotazione regolazione registri e posizione valvola, smontaggio<\/li>\n<li>pulizia e sgrassaggio in profondit\u00e0<\/li>\n<li>sostituzione ed aggiornamento elementi di tenuta per la parte pneumatica, idraulica e valvole di regolazione sul serbatoio<\/li>\n<li>rimontaggio con utilizzo di prodotti specifici (adesivo anaerobico sigillante sulle filettature , grasso ad altissima scorrevolezza specifico per sospensioni, lubricanti specifici)<\/li>\n<li>spurgo multiplo sottovuoto con pompa Andreani semi-automatica digitale ed olio Ohlins\u00a0(garantisce assenza di aria nel circuito idraulico-molto intricato-\u00a0garantendo costanza e durata delle prestazioni)<\/li>\n<li>pressurizzazione IFP con azoto<\/li>\n<li>sostituzione boccole DU se necessario (allegare sempre i riduttori)<\/li>\n<li>setup e test finale<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div>\n<div class=\"panel panel-default panel-odd\"><div class=\"panel-heading\"><a class=\"accordion-toggle collapsed\" data-toggle=\"collapse\" data-parent=\"#accordionname11\" href=\"#collapse111\"><h5><i class=\"icon-minus primary-color\"><\/i><i class=\"icon-plus\"><\/i>Tuning<\/h5><\/a><\/div><div id=\"collapse111\" class=\"panel-collapse collapse \"><div class=\"panel-body postclass\">\n<p><strong>Le opzioni possibili di tuning per questo ammortizzatore sono:<\/strong><\/p>\n<ul>\n<li>Aumento progressione (maggior sostegno a met\u00e0 corsa e finecorsa pi\u00f9 difficilmente raggiungibile)<\/li>\n<li>Per altre esigenze di taratura qualsiasi indicazione data nelle note verr\u00e0 presa in considerazione.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Manutenzione ordinaria per ammortizzatori Cane Creek DB Kitsuma Air<\/p>\n","protected":false},"featured_media":3062,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[18,41,44],"product_tag":[],"_links":{"self":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product\/3057"}],"collection":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/comments?post=3057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/media\/3062"}],"wp:attachment":[{"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/media?parent=3057"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product_cat?post=3057"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fluidworkssuspension.com\/store\/wp-json\/wp\/v2\/product_tag?post=3057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}